{"id":135,"date":"2018-06-21T07:00:30","date_gmt":"2018-06-21T05:00:30","guid":{"rendered":"http:\/\/audioactif.fr\/vhs\/?p=135"},"modified":"2018-09-17T15:29:18","modified_gmt":"2018-09-17T13:29:18","slug":"il-va-y-avoir-des-sequelles","status":"publish","type":"post","link":"https:\/\/audioactif.fr\/vhs\/2018\/06\/21\/il-va-y-avoir-des-sequelles\/","title":{"rendered":"Il va y avoir des s\u00e9quelles !"},"content":{"rendered":"<div style=\"text-align:center\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"750\" src=\"https:\/\/audioactif.fr\/vhs\/wp-content\/uploads\/sites\/4\/2018\/06\/die-hard-saga2.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Il va y avoir des s\u00e9quelles !\" title=\"Il va y avoir des s\u00e9quelles !\" srcset=\"https:\/\/audioactif.fr\/vhs\/wp-content\/uploads\/sites\/4\/2018\/06\/die-hard-saga2.jpg 750w, https:\/\/audioactif.fr\/vhs\/wp-content\/uploads\/sites\/4\/2018\/06\/die-hard-saga2-150x150.jpg 150w, https:\/\/audioactif.fr\/vhs\/wp-content\/uploads\/sites\/4\/2018\/06\/die-hard-saga2-300x300.jpg 300w, https:\/\/audioactif.fr\/vhs\/wp-content\/uploads\/sites\/4\/2018\/06\/die-hard-saga2-250x250.jpg 250w, https:\/\/audioactif.fr\/vhs\/wp-content\/uploads\/sites\/4\/2018\/06\/die-hard-saga2-125x125.jpg 125w, https:\/\/audioactif.fr\/vhs\/wp-content\/uploads\/sites\/4\/2018\/06\/die-hard-saga2-110x110.jpg 110w, https:\/\/audioactif.fr\/vhs\/wp-content\/uploads\/sites\/4\/2018\/06\/die-hard-saga2-420x420.jpg 420w, https:\/\/audioactif.fr\/vhs\/wp-content\/uploads\/sites\/4\/2018\/06\/die-hard-saga2-430x430.jpg 430w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/div><p>Attention attention, voici ce qui semble \u00eatre le dernier \u00e9pisode de la saison pour VHS &amp; CANAP\u00c9 et histoire de finir en apoth\u00e9ose toute l\u2019\u00e9quipe s&#8217;est rassemblait pour discuter de ce qui fait g\u00e9n\u00e9ralement d\u00e9bat au cin\u00e9ma&#8230; LES SUITES !!!<br \/>\nPoursuivre les aventures d&#8217;un film culte, cr\u00e9er une saga \u00e0 partir de rien ou tout simplement essayer de se faire du pognon sans forc\u00e9ment comprendre ce qui faisait l\u2019int\u00e9r\u00eat d&#8217;une oeuvre, la suite est complexe \u00e0 appr\u00e9hender et nous allons vous proposer ce qui pour la Team VHS fait qu&#8217;une suite est bonne&#8230; ou mauvaise !<\/p>\n<p>Pr\u00e9parez vous \u00e0 du d\u00e9bat, du fou rire et de la mauvaise foi&#8230; amusez vous bien !<\/p>\n<p><center><iframe loading=\"lazy\" src=\"https:\/\/widget.ausha.co\/index.html?podcastId=oKmrUmw8Q78b&amp;width=100%25&amp;color=%2372238E&amp;mode=single&amp;display=horizontal&amp;v=1\" width=\"100%\" height=\"undefined\" frameborder=\"0\"><\/iframe><\/center><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Attention attention, voici ce qui semble \u00eatre le dernier \u00e9pisode de la saison pour VHS &amp; CANAP\u00c9 et histoire de finir en apoth\u00e9ose toute l\u2019\u00e9quipe s&#8217;est rassemblait pour discuter de ce qui fait g\u00e9n\u00e9ralement d\u00e9bat au cin\u00e9ma&#8230; LES SUITES !!! Poursuivre les aventures d&#8217;un film culte, cr\u00e9er une saga \u00e0 partir de rien ou tout [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":"","fifu_image_url":"","fifu_image_alt":"","_vp_format_video_url":"","_vp_image_focal_point":[]},"categories":[2],"tags":[],"views":1160,"_links":{"self":[{"href":"https:\/\/audioactif.fr\/vhs\/wp-json\/wp\/v2\/posts\/135"}],"collection":[{"href":"https:\/\/audioactif.fr\/vhs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/audioactif.fr\/vhs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/audioactif.fr\/vhs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/audioactif.fr\/vhs\/wp-json\/wp\/v2\/comments?post=135"}],"version-history":[{"count":2,"href":"https:\/\/audioactif.fr\/vhs\/wp-json\/wp\/v2\/posts\/135\/revisions"}],"predecessor-version":[{"id":257,"href":"https:\/\/audioactif.fr\/vhs\/wp-json\/wp\/v2\/posts\/135\/revisions\/257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/audioactif.fr\/vhs\/wp-json\/wp\/v2\/media\/142"}],"wp:attachment":[{"href":"https:\/\/audioactif.fr\/vhs\/wp-json\/wp\/v2\/media?parent=135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/audioactif.fr\/vhs\/wp-json\/wp\/v2\/categories?post=135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/audioactif.fr\/vhs\/wp-json\/wp\/v2\/tags?post=135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}