{"id":243,"date":"2019-12-31T10:00:08","date_gmt":"2019-12-31T09:00:08","guid":{"rendered":"http:\/\/audioactif.fr\/podmonstrestresors\/?p=243"},"modified":"2019-12-31T09:26:09","modified_gmt":"2019-12-31T08:26:09","slug":"22-episode-10-cowboy","status":"publish","type":"post","link":"https:\/\/audioactif.fr\/podmonstrestresors\/2019\/12\/31\/22-episode-10-cowboy\/","title":{"rendered":"22 &#8211; Episode 10 : Cowboy"},"content":{"rendered":"<div style=\"text-align:center\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"450\" src=\"https:\/\/audioactif.fr\/podmonstrestresors\/wp-content\/uploads\/sites\/10\/2019\/11\/audioep10.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"22 &#8211; Episode 10 : Cowboy\" title=\"22 &#8211; Episode 10 : Cowboy\" srcset=\"https:\/\/audioactif.fr\/podmonstrestresors\/wp-content\/uploads\/sites\/10\/2019\/11\/audioep10.jpg 450w, https:\/\/audioactif.fr\/podmonstrestresors\/wp-content\/uploads\/sites\/10\/2019\/11\/audioep10-150x150.jpg 150w, https:\/\/audioactif.fr\/podmonstrestresors\/wp-content\/uploads\/sites\/10\/2019\/11\/audioep10-300x300.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/div><p>Pod Monstres Tr\u00e9sors, c&#8217;est le podcast dont vous \u00eates l&#8217;auditeur et o\u00f9 nous sommes le h\u00e9ros !<\/p>\n<p>Tous les mois Gaewen, Fonz &amp; Winston vont jouer des coudes pour ne pas mourir au d\u00e9tour d&#8217;une page. 1 Heure, 1 H\u00e9ros, 3 joueurs !<\/p>\n<p>Oyez Oyez ! Gaewen, Fonz &amp; Winston repartent \u00e0 l&#8217;aventure dans <em>La Nuit Du M\u00e9t\u00e9ore\u00a0<\/em> de Doug Headline et Dominique Monrocq avec leur fid\u00e8le super-h\u00e9ros Docteur Von Shark !<\/p>\n<p>Fonz a-t-il fait du t\u00e9l\u00e9achat dans une autre vie ? Winston arrivera-t-il a parler d&#8217;une star du porno dijonnaise ? Gaewen arrivera-t-elle \u00e0 ne pas rigoler ?! Allez-vous participer \u00e0 notre concours de dessin ?! Tout \u00e7a et plus encore sont \u00e0 d\u00e9couvrir dans notre \u00c9pisode 10 !<\/p>\n<p>On se retrouve en 2020 !<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/widget.ausha.co\/index.html?chanId=BNkVcJ75ZVKo&amp;showId=yv3gTmPRpe9b&amp;color=%2372238e&amp;display=horizontal&amp;v=2&amp;height=201px&amp;podcastId=Bq7vTZV10Agy\" width=\"510px\" height=\"201px\" frameborder=\"0\"><\/iframe><\/p>\n<p>Un grand merci \u00e0 Julien Van Egroo, compositeur de l&#8217;album <em>Welcome to Dunwich, <\/em>de nous autoriser \u00e0 utiliser son album comme musique d&#8217;ambiance. A \u00e9couter en int\u00e9gralit\u00e9 <a href=\"https:\/\/julienvanegroo.bandcamp.com\/releases\">ici<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Et comme promis, voici la silhouette a dessiner\/habiller pour notre concours Docteur Van Shark ! Aidez nous a trouver le meilleur costume pour le Docteur d&#8217;apr\u00e8s le vrai concours organiser par Hachette en 1986.<\/p>\n<p><a href=\"http:\/\/audioactif.fr\/podmonstrestresors\/wp-content\/uploads\/sites\/10\/2019\/12\/silhouette-super-hero.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-254\" src=\"http:\/\/audioactif.fr\/podmonstrestresors\/wp-content\/uploads\/sites\/10\/2019\/12\/silhouette-super-hero-1024x1024.jpg\" alt=\"\" width=\"450\" height=\"450\" srcset=\"https:\/\/audioactif.fr\/podmonstrestresors\/wp-content\/uploads\/sites\/10\/2019\/12\/silhouette-super-hero-1024x1024.jpg 1024w, https:\/\/audioactif.fr\/podmonstrestresors\/wp-content\/uploads\/sites\/10\/2019\/12\/silhouette-super-hero-300x300.jpg 300w, https:\/\/audioactif.fr\/podmonstrestresors\/wp-content\/uploads\/sites\/10\/2019\/12\/silhouette-super-hero-150x150.jpg 150w, https:\/\/audioactif.fr\/podmonstrestresors\/wp-content\/uploads\/sites\/10\/2019\/12\/silhouette-super-hero-768x768.jpg 768w, https:\/\/audioactif.fr\/podmonstrestresors\/wp-content\/uploads\/sites\/10\/2019\/12\/silhouette-super-hero.jpg 1276w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> &hellip;<\/p>\n","protected":false},"author":926,"featured_media":227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":"","fifu_image_url":"","fifu_image_alt":"","_vp_format_video_url":"","_vp_image_focal_point":[]},"categories":[4],"tags":[],"views":1405,"_links":{"self":[{"href":"https:\/\/audioactif.fr\/podmonstrestresors\/wp-json\/wp\/v2\/posts\/243"}],"collection":[{"href":"https:\/\/audioactif.fr\/podmonstrestresors\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/audioactif.fr\/podmonstrestresors\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/audioactif.fr\/podmonstrestresors\/wp-json\/wp\/v2\/users\/926"}],"replies":[{"embeddable":true,"href":"https:\/\/audioactif.fr\/podmonstrestresors\/wp-json\/wp\/v2\/comments?post=243"}],"version-history":[{"count":20,"href":"https:\/\/audioactif.fr\/podmonstrestresors\/wp-json\/wp\/v2\/posts\/243\/revisions"}],"predecessor-version":[{"id":265,"href":"https:\/\/audioactif.fr\/podmonstrestresors\/wp-json\/wp\/v2\/posts\/243\/revisions\/265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/audioactif.fr\/podmonstrestresors\/wp-json\/wp\/v2\/media\/227"}],"wp:attachment":[{"href":"https:\/\/audioactif.fr\/podmonstrestresors\/wp-json\/wp\/v2\/media?parent=243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/audioactif.fr\/podmonstrestresors\/wp-json\/wp\/v2\/categories?post=243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/audioactif.fr\/podmonstrestresors\/wp-json\/wp\/v2\/tags?post=243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}